{"id":2821,"date":"2025-04-15T15:51:52","date_gmt":"2025-04-15T13:51:52","guid":{"rendered":"https:\/\/bestveronaguides.it\/?p=2821"},"modified":"2025-04-18T22:24:18","modified_gmt":"2025-04-18T20:24:18","slug":"le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020","status":"publish","type":"post","link":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/","title":{"rendered":"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2821\" class=\"elementor elementor-2821 elementor-2783\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a4e535 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a4e535\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81bf3f9\" data-id=\"81bf3f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-982c021 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"982c021\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4509b6f\" data-id=\"4509b6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f64d263 elementor-widget elementor-widget-text-editor\" data-id=\"f64d263\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Le jardin de la Renaissance.\u00a0<\/h2><br><p>Le <strong>Jardin Giusti<\/strong> est consid\u00e9r\u00e9 l\u2019un des symbole de la V\u00e9n\u00e9tie parmi les <strong>jardins en style italien<\/strong> de la haute <strong>Renaissance<\/strong>. Dans cette p\u00e9riode historique les arts s\u2019inspirent \u00e0 la culture classique de Rome et de la Gr\u00e8ce; la raison,l\u2019ordre et la symmetrie sont les\u00a0 principes dominants. En effet, dans la structure du <strong>jardin<\/strong> on trouve tous ces \u00e9l\u00e9ments. La couleur verte des plantes, mais surtout les plantes en feuilles persistantes, dominent le jardin, car ce type de plantes ne perdent pas leur fueillage pour rena\u00eetre le printemps, ce qui ne donnait pas l\u2019id\u00e9e de la mort et de la renaissance, mais de quelque chose qui ne change pas avec le passage du temps. Des plantes, comme les <strong>cypr\u00e8s<\/strong>, donnent de la structure et d\u00e9corent un jardin avec leur forme en pyramide. <strong>L\u2019art topiaire<\/strong>, h\u00e9ritage de la culture romaine, reappara\u00eet m\u00eame ici, les<strong> haies de buis<\/strong> qui forment des figure g\u00e9om\u00e9triques tout autour des statues et des fontaines.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2b8f9c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2b8f9c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dfb921d\" data-id=\"dfb921d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5d98d8 elementor-widget elementor-widget-text-editor\" data-id=\"d5d98d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>La cr\u00e8ation du Jardin Giusti et son parcours dans le temps.<\/h2><br><p>Le Jardin Giusti fut cr\u00e9e par le Comte <strong>Agostino Giust<\/strong>i vers l\u2019ann\u00e9e 1585, et depuis lors il appartient \u00e0 la m\u00eame famille qui est arriv\u00e9 \u00e0 <strong>V\u00e9rone<\/strong> en exile de la Toscane, \u00e0 l\u2019\u00e9poque des luttes entre <strong>Guelfes<\/strong> et <strong>Gibellins<\/strong>. La famille s\u2019est \u00e9tablie \u00e0 V\u00e9rone, ville gibelline, et sera connue dans le domaine de l\u2019industrie textile, mais en m\u00eame temps, aura de l\u2019influence dans le cadre de la culture de la ville. Au cours de la Renaissance la famille fera partie des membres de <strong>l\u2019Acad\u00e9mie<\/strong> <strong>Philharmonique<\/strong> de V\u00e9rone et son si\u00e8ge se trouvera m\u00eame dans les maisons de la famille Giusti. Dans le jardin de la demeure avaient lieu des spectacles de th\u00e9\u00e2tre et des concerts; peu \u00e0 peu les propri\u00e9t\u00e9s seront reli\u00e9es et sera na\u00eet le palais actuel.<\/p><br><p>Le jardin, \u00e0 travers les si\u00e8cles, a \u00e9t\u00e9 la destination des personnages importans, de la taille de <strong>Goethe<\/strong>, <strong>Mozart<\/strong> et Charles de Brosses. Encore \u00e0 present, le jardin est visit\u00e9 par de nombreux touristes, qui trouvent au milieu de la ville non seulement un chef d\u2019oeuvre d\u2019art de la Renaissance, mais aussi une oasis de paix et tranquilit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0d1212 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0d1212\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0747dd1\" data-id=\"0747dd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa0cbed elementor-widget elementor-widget-image\" data-id=\"aa0cbed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"259\" src=\"https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-cipresso-goethe-1024x331.jpg\" class=\"attachment-large size-large wp-image-2798\" alt=\"\" srcset=\"https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-cipresso-goethe-1024x331.jpg 1024w, https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-cipresso-goethe-500x162.jpg 500w, https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-cipresso-goethe-768x248.jpg 768w, https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-cipresso-goethe-1536x497.jpg 1536w, https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-cipresso-goethe.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4932e8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4932e8e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea6c20e\" data-id=\"ea6c20e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-492316d elementor-widget elementor-widget-text-editor\" data-id=\"492316d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>La temp\u00eate de l&rsquo;ann\u00e9e 2020.<\/h2><br><p>Malheuresement les changements climatiques des derni\u00e8res ann\u00e9es deviennent \u00e9vidents m\u00eame \u00e0 V\u00e9rone; surtout pendant l\u2019\u00e9t\u00e9 des temp\u00eates et des orages assez violents arrivent soudainement.<\/p><br><p>L\u2019ann\u00e9e 2020 a \u00e9t\u00e9 une ann\u00e9e tr\u00e8s dure pour l\u2019Italie, et aussi pour le monde entier. Nous nous en souviendrons toujours comme l\u2019ann\u00e9e du \u201c<strong>Covid<\/strong>\u201d, ce virus inconnu, qui a provoqu\u00e9 tant de mort et de souffrance, et nous a men\u00e9 \u00e0 l\u2019isolement et aux <strong>lockdowns<\/strong>. Mais comme si tout ce qui se passait n\u2019\u00e8tait pas suffisant, le 23 Ao\u00fbt 2020, un orage violent avec de la gr\u00e8le\u00a0 et du vent tr\u00e8s fort s\u2019est abattue sur V\u00e9rone. Le Jardin Giusti a \u00e9t\u00e9 l\u2019une des victimes de cette violente temp\u00eate, qui a laiss\u00e8 un spectacle de d\u00e9solation dans le jardin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5afa7d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5afa7d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a8dd1c6\" data-id=\"a8dd1c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edba94e elementor-widget elementor-widget-image\" data-id=\"edba94e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"259\" src=\"https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-danni-2020-1024x331.jpg\" class=\"attachment-large size-large wp-image-2804\" alt=\"\" srcset=\"https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-danni-2020-1024x331.jpg 1024w, https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-danni-2020-500x162.jpg 500w, https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-danni-2020-768x248.jpg 768w, https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-danni-2020-1536x497.jpg 1536w, https:\/\/bestveronaguides.it\/media\/bvg-g-giusti-danni-2020.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b25e80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b25e80\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0e4666\" data-id=\"c0e4666\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5743732 elementor-widget elementor-widget-text-editor\" data-id=\"5743732\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>L&rsquo;\u00e8valuation des d\u00e8g\u00e2ts.<\/h2><br><p>Plusieurs arbres, parmi lesquels des<strong> celtis <\/strong>australis et des cypr\u00e8s sont tomb\u00e9s en endommageant des parties des remparts qui entourent le jardin, ainsi que l\u2019All\u00e9e des Cypr\u00e8s et des parties du labyrinthe. Beaucoup des cypr\u00e8s avaient \u00e9t\u00e9 plant\u00e9s apr\u00e8s la fin de la deuxi\u00e8me Guerre Mondiale, apr\u00e8s que les bombes, vis\u00e9es \u00e0 d\u00e8truire la gare de V\u00e9rone, sont tomb\u00e9es par hasard dans le jardin. Il s\u2019agissait des arbres de grandes dimensions dispos\u00e9s sur une all\u00e9e qui sont tomb\u00e9s les uns sur les autres, et quelques uns d\u2019entre eux sur le <strong>labyrinthe<\/strong>, qui avait \u00e9t\u00e9 d\u00e9j\u00e0 restaur\u00e9 dans les<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f9d288a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f9d288a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63841f0\" data-id=\"63841f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81d9368 elementor-widget elementor-widget-image\" data-id=\"81d9368\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"259\" src=\"https:\/\/bestveronaguides.it\/media\/bvg-il-cipresso-di-goethe-caduto-1024x331.jpg\" class=\"attachment-large size-large wp-image-2810\" alt=\"\" srcset=\"https:\/\/bestveronaguides.it\/media\/bvg-il-cipresso-di-goethe-caduto-1024x331.jpg 1024w, https:\/\/bestveronaguides.it\/media\/bvg-il-cipresso-di-goethe-caduto-500x162.jpg 500w, https:\/\/bestveronaguides.it\/media\/bvg-il-cipresso-di-goethe-caduto-768x248.jpg 768w, https:\/\/bestveronaguides.it\/media\/bvg-il-cipresso-di-goethe-caduto-1536x497.jpg 1536w, https:\/\/bestveronaguides.it\/media\/bvg-il-cipresso-di-goethe-caduto.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6591e6e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6591e6e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e54c42e\" data-id=\"e54c42e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b396fb elementor-widget elementor-widget-text-editor\" data-id=\"9b396fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Le cypr\u00e9s de Goethe.<\/h2><br><p>&nbsp;<\/p><br><p>De toutes fa\u00e7ons, le symbole le plus important, \u00e9tait le cypress historique, appel\u00e9 \u201c l<strong>e cypr\u00e8s de Goethe\u00a0\u00bb<\/strong>, parce que le grand <strong>po\u00e8te allemand<\/strong>, l\u2019avait mentionn\u00e9 dans le livre sur son voyage en Italie, en 1786. Goethe aurait d\u00fb prendre quelque petits rameaux de l\u2019arbre et il les portaient avec lui en tant qu\u2019il se promenait \u00e0 V\u00e9rone. Des visiteurs de toutes l\u2019Europe, ainsi que d\u2019autres parties du monde venaient le voir. M\u00eame s\u2019il \u00e8tait d\u00e9j\u00e0 assez affaibli, les propri\u00e9taires du jardin, la famille<strong> Giusti,<\/strong> avec les jardiniers, avaient essay\u00e9 de faire tout ce que possible pour le sauver. Cependant la force impitoyable du vent ce jour l\u00e0 est r\u00e9ussie \u00e0 d\u00e9raciner l\u2019arbre compl\u00e8tement. Tous les efforts pour essayer de le sauver ont \u00e9t\u00e9 inutiles, et comme \u00e7a le jardin a perdu l\u2019un des ses grands symboles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72114f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72114f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de1bd51\" data-id=\"de1bd51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf41adb elementor-widget elementor-widget-text-editor\" data-id=\"bf41adb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Apr\u00e8s la temp\u00eate le soleil brille toujours \u00e0 nouveau.<\/h2><br><p>N\u00e9anmoins, petit \u00e8 petit l\u2019ordre a \u00e9t\u00e9 r\u00e9tabli et quelques jours apr\u00e8s la temp\u00eate le jardin a \u00e9t\u00e9 r\u00e9ouvert. Dans les derni\u00e8res ann\u00e9es les cypr\u00e8s ont \u00e9t\u00e9 replant\u00e9s et le labyrinthe ainsi que les haies,endommag\u00e9es par l\u2019orage, ont \u00e9t\u00e9 restaur\u00e9es. Les cypr\u00e8s actuellement sont tr\u00e8s petits par rapport \u00e0 ceux qui \u00e8taient l\u00e0 auparavant mais, ils pousseront et nous permettrons d\u2019aller en arri\u00e8re dans l\u2019histoire\u00a0 jusqu\u2019au temps d\u2019<strong>Agostino Giusti<\/strong> pour admirer le joyau na\u00eet de sa grande cr\u00e9ativit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-881d5bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"881d5bd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4bd887\" data-id=\"d4bd887\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8862176 elementor-widget elementor-widget-text-editor\" data-id=\"8862176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Ut elit tellus, luctus nec ullamcorper mattis, pulvinar dapibus leo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le jardin de la Renaissance.\u00a0 Le Jardin Giusti est consid\u00e9r\u00e9 l\u2019un des symbole de la V\u00e9n\u00e9tie parmi les jardins en style italien de la haute Renaissance. Dans cette p\u00e9riode historique les arts s\u2019inspirent \u00e0 la culture classique de Rome et de la Gr\u00e8ce; la raison,l\u2019ordre et la symmetrie sont les\u00a0 principes dominants. En effet, dans [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":2830,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"class_list":["post-2821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020. - Best Verona Guides<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020. - Best Verona Guides\" \/>\n<meta property=\"og:description\" content=\"Le jardin de la Renaissance.\u00a0 Le Jardin Giusti est consid\u00e9r\u00e9 l\u2019un des symbole de la V\u00e9n\u00e9tie parmi les jardins en style italien de la haute Renaissance. Dans cette p\u00e9riode historique les arts s\u2019inspirent \u00e0 la culture classique de Rome et de la Gr\u00e8ce; la raison,l\u2019ordre et la symmetrie sont les\u00a0 principes dominants. En effet, dans [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Best Verona Guides\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-15T13:51:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-18T20:24:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bestveronaguides.it\/media\/giardino-giusti-bvg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"621\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gustavo Romano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Romano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/\"},\"author\":{\"name\":\"Gustavo Romano\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/#\\\/schema\\\/person\\\/bfe2e4c4645cf787fc0e4c91f27a7908\"},\"headline\":\"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020.\",\"datePublished\":\"2025-04-15T13:51:52+00:00\",\"dateModified\":\"2025-04-18T20:24:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/\"},\"wordCount\":966,\"publisher\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/giardino-giusti-bvg.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/\",\"name\":\"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020. - Best Verona Guides\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/giardino-giusti-bvg.jpg\",\"datePublished\":\"2025-04-15T13:51:52+00:00\",\"dateModified\":\"2025-04-18T20:24:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/giardino-giusti-bvg.jpg\",\"contentUrl\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/giardino-giusti-bvg.jpg\",\"width\":1920,\"height\":621},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/\",\"name\":\"Best Verona Guides\",\"description\":\"La tua guida in un attimo\",\"publisher\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/#organization\",\"name\":\"Associazione Assoguide Verona\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/logo.png\",\"width\":444,\"height\":237,\"caption\":\"Associazione Assoguide Verona\"},\"image\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/#\\\/schema\\\/person\\\/bfe2e4c4645cf787fc0e4c91f27a7908\",\"name\":\"Gustavo Romano\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/fr\\\/guide\\\/gustavoromano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020. - Best Verona Guides","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020. - Best Verona Guides","og_description":"Le jardin de la Renaissance.\u00a0 Le Jardin Giusti est consid\u00e9r\u00e9 l\u2019un des symbole de la V\u00e9n\u00e9tie parmi les jardins en style italien de la haute Renaissance. Dans cette p\u00e9riode historique les arts s\u2019inspirent \u00e0 la culture classique de Rome et de la Gr\u00e8ce; la raison,l\u2019ordre et la symmetrie sont les\u00a0 principes dominants. En effet, dans [&hellip;]","og_url":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/","og_site_name":"Best Verona Guides","article_published_time":"2025-04-15T13:51:52+00:00","article_modified_time":"2025-04-18T20:24:18+00:00","og_image":[{"width":1920,"height":621,"url":"https:\/\/bestveronaguides.it\/media\/giardino-giusti-bvg.jpg","type":"image\/jpeg"}],"author":"Gustavo Romano","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gustavo Romano","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/#article","isPartOf":{"@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/"},"author":{"name":"Gustavo Romano","@id":"https:\/\/bestveronaguides.it\/fr\/#\/schema\/person\/bfe2e4c4645cf787fc0e4c91f27a7908"},"headline":"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020.","datePublished":"2025-04-15T13:51:52+00:00","dateModified":"2025-04-18T20:24:18+00:00","mainEntityOfPage":{"@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/"},"wordCount":966,"publisher":{"@id":"https:\/\/bestveronaguides.it\/fr\/#organization"},"image":{"@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/bestveronaguides.it\/media\/giardino-giusti-bvg.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/","url":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/","name":"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020. - Best Verona Guides","isPartOf":{"@id":"https:\/\/bestveronaguides.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/#primaryimage"},"image":{"@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/bestveronaguides.it\/media\/giardino-giusti-bvg.jpg","datePublished":"2025-04-15T13:51:52+00:00","dateModified":"2025-04-18T20:24:18+00:00","breadcrumb":{"@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/#primaryimage","url":"https:\/\/bestveronaguides.it\/media\/giardino-giusti-bvg.jpg","contentUrl":"https:\/\/bestveronaguides.it\/media\/giardino-giusti-bvg.jpg","width":1920,"height":621},{"@type":"BreadcrumbList","@id":"https:\/\/bestveronaguides.it\/fr\/le-jardin-giusti-et-la-renaissance-apres-la-tempete-de-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bestveronaguides.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Le Jardin Giusti et la renaissance apr\u00e8s la temp\u00eate de 2020."}]},{"@type":"WebSite","@id":"https:\/\/bestveronaguides.it\/fr\/#website","url":"https:\/\/bestveronaguides.it\/fr\/","name":"Best Verona Guides","description":"La tua guida in un attimo","publisher":{"@id":"https:\/\/bestveronaguides.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bestveronaguides.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bestveronaguides.it\/fr\/#organization","name":"Associazione Assoguide Verona","url":"https:\/\/bestveronaguides.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bestveronaguides.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/bestveronaguides.it\/media\/logo.png","contentUrl":"https:\/\/bestveronaguides.it\/media\/logo.png","width":444,"height":237,"caption":"Associazione Assoguide Verona"},"image":{"@id":"https:\/\/bestveronaguides.it\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bestveronaguides.it\/fr\/#\/schema\/person\/bfe2e4c4645cf787fc0e4c91f27a7908","name":"Gustavo Romano","url":"https:\/\/bestveronaguides.it\/fr\/guide\/gustavoromano\/"}]}},"_links":{"self":[{"href":"https:\/\/bestveronaguides.it\/fr\/wp-json\/wp\/v2\/posts\/2821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestveronaguides.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bestveronaguides.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bestveronaguides.it\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/bestveronaguides.it\/fr\/wp-json\/wp\/v2\/comments?post=2821"}],"version-history":[{"count":0,"href":"https:\/\/bestveronaguides.it\/fr\/wp-json\/wp\/v2\/posts\/2821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestveronaguides.it\/fr\/wp-json\/wp\/v2\/media\/2830"}],"wp:attachment":[{"href":"https:\/\/bestveronaguides.it\/fr\/wp-json\/wp\/v2\/media?parent=2821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}