{"id":1679,"date":"2022-12-11T15:29:34","date_gmt":"2022-12-11T14:29:34","guid":{"rendered":"https:\/\/bestveronaguides.it\/verona-und-die-oper\/"},"modified":"2022-12-11T15:29:42","modified_gmt":"2022-12-11T14:29:42","slug":"verona-und-die-oper","status":"publish","type":"post","link":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/","title":{"rendered":"Verona und die Oper"},"content":{"rendered":"\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\">Die italienische Oper wurde in Florenz im XVI. <span lang=\"en-US\">Jahrhundert geboren und im Laufe der Zeit ist zum Stil geworden, der die italienische Musik auf der Welt kennzeichnet.<\/span><\/span><\/p><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span lang=\"en-US\">Verona und die Oper sind eng verbunden, und vom Anfang des XX. Jahrhundert in den Sommermonaten kann man in der Luft das Belcanto sp\u00fcren.<\/span><\/span><\/p><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span lang=\"en-US\">Manchmal, solange man auf die kleinen Gassen im Zentrum spaziert, kann man die Stimme eines S\u00e4ngers h\u00f6ren, der f\u00fcr den Abend in der Arena probt.\u00a0<\/span><\/span><\/p><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span lang=\"en-US\">\u0170ber ein Jahrhundert Geschichte begleitet das Festival, das von der Idee des Tenors Giovanni Zenatello 1913 geboren wurde und zu der wichtigsten kulturellen Veranstantung in Verona wurde.<\/span><\/span><\/p><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span lang=\"en-US\">Die Festspiele finden im Rahmen einer 2000- j\u00e4hrige Konstruktion statt, die f\u00fcr grausame Gladiatorenspiele entstanden ist und im Sommer wird zum gr\u00f6\u00dften Freilichttheater der Welt.<\/span><\/span><\/p>\n\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span lang=\"en-US\">Die Operfestspiele von Verona haben die Stadt weltber\u00fchmt gemacht, genauso wie die Geschichte von Romeo und Julia.<\/span><\/span><\/p><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span lang=\"en-US\">\u0170ber ein Jahrhundert Geschichte begleitet das Festival, das von der Idee des Tenors Giovanni Zenatello 1913 geboren wurde und zu der wichtigsten kulturellen Veranstantung in Verona wurde.<\/span><\/span><\/p><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span lang=\"en-US\">Die Festspiele finden im Rahmen einer 2000- j\u00e4hrige Konstruktion statt, die f\u00fcr grausame Gladiatorenspiele entstanden ist und im Sommer wird zum gr\u00f6\u00dften Freilichttheater der Welt.<\/span><\/span><\/p><p><br\/><\/p>\n\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><strong><span lang=\"en-US\">Zusammenfassend<\/span><\/strong><span lang=\"en-US\">:<\/span><\/span><\/p><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span lang=\"en-US\">Bei dieser tour werden wir eine Reise in die Geschichte machen, von der Geburt der Stadt in der R\u00f6merzeit und der Ursprung des r\u00f6mischen Amphitheaters bis zu unserer Zeit wenn die Arena die B\u00fchne der Musik.<\/span><\/span><\/p><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\" data-mce-style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span lang=\"en-US\">Entdecken wir zusammen die Opernwelt und die Arena von Verona.<\/span><\/span><\/p>\n\n<p><span style=\"font-family: verdana, geneva, sans-serif;\" data-mce-style=\"font-family: verdana, geneva, sans-serif;\"><strong>Dauer<\/strong> : ab 2 Stunden<\/span><\/p>\n\n<p><span style=\"font-family: verdana, geneva, sans-serif;\" data-mce-style=\"font-family: verdana, geneva, sans-serif;\"><strong>Tarife<\/strong>: ab 75\u20ac pro Stunde<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seit 1913, der H\u00f6hepunkt des kulturelles Lebens in Verona sind die Operfestspiele in der Arena von Verona.<\/p>\n","protected":false},"author":8,"featured_media":1361,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"class_list":["post-1679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verona und die Oper - Best Verona Guides<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verona und die Oper - Best Verona Guides\" \/>\n<meta property=\"og:description\" content=\"Seit 1913, der H\u00f6hepunkt des kulturelles Lebens in Verona sind die Operfestspiele in der Arena von Verona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/\" \/>\n<meta property=\"og:site_name\" content=\"Best Verona Guides\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-11T14:29:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-11T14:29:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bestveronaguides.it\/media\/Interno-arena-opera.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"621\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Erika Montresor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erika Montresor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/\"},\"author\":{\"name\":\"Erika Montresor\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/#\\\/schema\\\/person\\\/7fc31d0f457f8cdfe09e266b4fa81c4f\"},\"headline\":\"Verona und die Oper\",\"datePublished\":\"2022-12-11T14:29:34+00:00\",\"dateModified\":\"2022-12-11T14:29:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/\"},\"wordCount\":267,\"publisher\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/Interno-arena-opera.webp\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/\",\"name\":\"Verona und die Oper - Best Verona Guides\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/Interno-arena-opera.webp\",\"datePublished\":\"2022-12-11T14:29:34+00:00\",\"dateModified\":\"2022-12-11T14:29:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/Interno-arena-opera.webp\",\"contentUrl\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/Interno-arena-opera.webp\",\"width\":1920,\"height\":621},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/verona-und-die-oper\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verona und die Oper\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/\",\"name\":\"Best Verona Guides\",\"description\":\"La tua guida in un attimo\",\"publisher\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/#organization\",\"name\":\"Associazione Assoguide Verona\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/bestveronaguides.it\\\/media\\\/logo.png\",\"width\":444,\"height\":237,\"caption\":\"Associazione Assoguide Verona\"},\"image\":{\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/#\\\/schema\\\/person\\\/7fc31d0f457f8cdfe09e266b4fa81c4f\",\"name\":\"Erika Montresor\",\"description\":\"Sono appassionata di Verona e mi piace farla conoscere in tutta la sua bellezza ai numerosi visitatori che ogni anno popolano le vie del centro\",\"sameAs\":[\"erikam_veronawithaguide\"],\"url\":\"https:\\\/\\\/bestveronaguides.it\\\/de\\\/guide\\\/erikamontresor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verona und die Oper - Best Verona Guides","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/","og_locale":"de_DE","og_type":"article","og_title":"Verona und die Oper - Best Verona Guides","og_description":"Seit 1913, der H\u00f6hepunkt des kulturelles Lebens in Verona sind die Operfestspiele in der Arena von Verona.","og_url":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/","og_site_name":"Best Verona Guides","article_published_time":"2022-12-11T14:29:34+00:00","article_modified_time":"2022-12-11T14:29:42+00:00","og_image":[{"width":1920,"height":621,"url":"https:\/\/bestveronaguides.it\/media\/Interno-arena-opera.webp","type":"image\/webp"}],"author":"Erika Montresor","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Erika Montresor","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/#article","isPartOf":{"@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/"},"author":{"name":"Erika Montresor","@id":"https:\/\/bestveronaguides.it\/de\/#\/schema\/person\/7fc31d0f457f8cdfe09e266b4fa81c4f"},"headline":"Verona und die Oper","datePublished":"2022-12-11T14:29:34+00:00","dateModified":"2022-12-11T14:29:42+00:00","mainEntityOfPage":{"@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/"},"wordCount":267,"publisher":{"@id":"https:\/\/bestveronaguides.it\/de\/#organization"},"image":{"@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/#primaryimage"},"thumbnailUrl":"https:\/\/bestveronaguides.it\/media\/Interno-arena-opera.webp","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/","url":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/","name":"Verona und die Oper - Best Verona Guides","isPartOf":{"@id":"https:\/\/bestveronaguides.it\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/#primaryimage"},"image":{"@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/#primaryimage"},"thumbnailUrl":"https:\/\/bestveronaguides.it\/media\/Interno-arena-opera.webp","datePublished":"2022-12-11T14:29:34+00:00","dateModified":"2022-12-11T14:29:42+00:00","breadcrumb":{"@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/#primaryimage","url":"https:\/\/bestveronaguides.it\/media\/Interno-arena-opera.webp","contentUrl":"https:\/\/bestveronaguides.it\/media\/Interno-arena-opera.webp","width":1920,"height":621},{"@type":"BreadcrumbList","@id":"https:\/\/bestveronaguides.it\/de\/verona-und-die-oper\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bestveronaguides.it\/de\/"},{"@type":"ListItem","position":2,"name":"Verona und die Oper"}]},{"@type":"WebSite","@id":"https:\/\/bestveronaguides.it\/de\/#website","url":"https:\/\/bestveronaguides.it\/de\/","name":"Best Verona Guides","description":"La tua guida in un attimo","publisher":{"@id":"https:\/\/bestveronaguides.it\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bestveronaguides.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/bestveronaguides.it\/de\/#organization","name":"Associazione Assoguide Verona","url":"https:\/\/bestveronaguides.it\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bestveronaguides.it\/de\/#\/schema\/logo\/image\/","url":"https:\/\/bestveronaguides.it\/media\/logo.png","contentUrl":"https:\/\/bestveronaguides.it\/media\/logo.png","width":444,"height":237,"caption":"Associazione Assoguide Verona"},"image":{"@id":"https:\/\/bestveronaguides.it\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bestveronaguides.it\/de\/#\/schema\/person\/7fc31d0f457f8cdfe09e266b4fa81c4f","name":"Erika Montresor","description":"Sono appassionata di Verona e mi piace farla conoscere in tutta la sua bellezza ai numerosi visitatori che ogni anno popolano le vie del centro","sameAs":["erikam_veronawithaguide"],"url":"https:\/\/bestveronaguides.it\/de\/guide\/erikamontresor\/"}]}},"_links":{"self":[{"href":"https:\/\/bestveronaguides.it\/de\/wp-json\/wp\/v2\/posts\/1679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestveronaguides.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bestveronaguides.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bestveronaguides.it\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/bestveronaguides.it\/de\/wp-json\/wp\/v2\/comments?post=1679"}],"version-history":[{"count":0,"href":"https:\/\/bestveronaguides.it\/de\/wp-json\/wp\/v2\/posts\/1679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestveronaguides.it\/de\/wp-json\/wp\/v2\/media\/1361"}],"wp:attachment":[{"href":"https:\/\/bestveronaguides.it\/de\/wp-json\/wp\/v2\/media?parent=1679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}